{"id":19692,"date":"2022-12-14T11:49:07","date_gmt":"2022-12-14T16:49:07","guid":{"rendered":"https:\/\/sdc-cotedesneiges.ca\/evenements\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/"},"modified":"2023-03-03T21:20:08","modified_gmt":"2023-03-04T02:20:08","slug":"exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes","status":"publish","type":"evenements","link":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/","title":{"rendered":"Exhibit : \u00c0 travers les secrets &#8211; l&#8217;art de cr\u00e9er des espaces entre les lignes"},"content":{"rendered":"\n<p>Discover a brand new exhibition of contemporary art at the Maison de la culture in C\u00f4te-des-Neiges<\/p>\n\n\n\n<p>&#8220;Through Secrets : The Art of Creating Spaces Between the Lines&#8221; includes works by contemporary artists whose work explores desire, interpersonal relationships, community connections, and critical approaches to algorithms and artificial intelligence.<\/p>\n\n\n\n<p>Check out all the details : <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-bleu-color\"><a href=\"https:\/\/montreal.ca\/evenements\/travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes-40658?fbclid=IwAR3pxCgSK6dB3a4mf1sIRTyUPz47X_Tzk5u7NkSBFl8OYgIi8PYsu0beaFI\" target=\"_blank\" rel=\"noreferrer noopener\">here<\/a><\/mark><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Discover a brand new exhibition of contemporary art at the Maison de la culture in&#8230; <a class=\"read-more\" href=\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/\">Read More <i class=\"fas fa-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"featured_media":19686,"menu_order":107,"template":"","class_list":["post-19692","evenements","type-evenements","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exhibit : \u00c0 travers les secrets - l&#039;art de cr\u00e9er des espaces entre les lignes - SDC C\u00f4te-des-Neiges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exhibit : \u00c0 travers les secrets - l&#039;art de cr\u00e9er des espaces entre les lignes - SDC C\u00f4te-des-Neiges\" \/>\n<meta property=\"og:description\" content=\"Discover a brand new exhibition of contemporary art at the Maison de la culture in... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/\" \/>\n<meta property=\"og:site_name\" content=\"SDC C\u00f4te-des-Neiges\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sdc.cotedesneiges\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-04T02:20:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/12\/SDCCDN2022_ATLCDA-1024x575.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/\",\"name\":\"Exhibit : \u00c0 travers les secrets - l'art de cr\u00e9er des espaces entre les lignes - SDC C\u00f4te-des-Neiges\",\"isPartOf\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/12\/SDCCDN2022_ATLCDA.png\",\"datePublished\":\"2022-12-14T16:49:07+00:00\",\"dateModified\":\"2023-03-04T02:20:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#primaryimage\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/12\/SDCCDN2022_ATLCDA.png\",\"contentUrl\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/12\/SDCCDN2022_ATLCDA.png\",\"width\":2865,\"height\":1610},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/sdc-cotedesneiges.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exhibit : \u00c0 travers les secrets &#8211; l&rsquo;art de cr\u00e9er des espaces entre les lignes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#website\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/en\/\",\"name\":\"SDC C\u00f4te-des-Neiges\",\"description\":\"Organisme \u00e0 but non-lucratif cr\u00e9\u00e9 en 2018, la SDC C\u00f4te-des-Neiges regroupe 230 commer\u00e7ants et professionnels.\",\"publisher\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sdc-cotedesneiges.ca\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#organization\",\"name\":\"SDC C\u00f4te-des-Neiges\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2020\/05\/logo-sdc-cote-des-neiges.png\",\"contentUrl\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2020\/05\/logo-sdc-cote-des-neiges.png\",\"width\":1221,\"height\":1290,\"caption\":\"SDC C\u00f4te-des-Neiges\"},\"image\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sdc.cotedesneiges\/\",\"https:\/\/www.instagram.com\/sdc.cotedesneiges\/\",\"https:\/\/www.linkedin.com\/company\/sdc-cotedesneiges\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exhibit : \u00c0 travers les secrets - l'art de cr\u00e9er des espaces entre les lignes - SDC C\u00f4te-des-Neiges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/","og_locale":"en_US","og_type":"article","og_title":"Exhibit : \u00c0 travers les secrets - l'art de cr\u00e9er des espaces entre les lignes - SDC C\u00f4te-des-Neiges","og_description":"Discover a brand new exhibition of contemporary art at the Maison de la culture in... Read More","og_url":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/","og_site_name":"SDC C\u00f4te-des-Neiges","article_publisher":"https:\/\/www.facebook.com\/sdc.cotedesneiges\/","article_modified_time":"2023-03-04T02:20:08+00:00","og_image":[{"width":1024,"height":575,"url":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/12\/SDCCDN2022_ATLCDA-1024x575.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/","url":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/","name":"Exhibit : \u00c0 travers les secrets - l'art de cr\u00e9er des espaces entre les lignes - SDC C\u00f4te-des-Neiges","isPartOf":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#primaryimage"},"image":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#primaryimage"},"thumbnailUrl":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/12\/SDCCDN2022_ATLCDA.png","datePublished":"2022-12-14T16:49:07+00:00","dateModified":"2023-03-04T02:20:08+00:00","breadcrumb":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#primaryimage","url":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/12\/SDCCDN2022_ATLCDA.png","contentUrl":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/12\/SDCCDN2022_ATLCDA.png","width":2865,"height":1610},{"@type":"BreadcrumbList","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/exposition-a-travers-les-secrets-lart-de-creer-des-espaces-entre-les-lignes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sdc-cotedesneiges.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Exhibit : \u00c0 travers les secrets &#8211; l&rsquo;art de cr\u00e9er des espaces entre les lignes"}]},{"@type":"WebSite","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#website","url":"https:\/\/sdc-cotedesneiges.ca\/en\/","name":"SDC C\u00f4te-des-Neiges","description":"Organisme \u00e0 but non-lucratif cr\u00e9\u00e9 en 2018, la SDC C\u00f4te-des-Neiges regroupe 230 commer\u00e7ants et professionnels.","publisher":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sdc-cotedesneiges.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#organization","name":"SDC C\u00f4te-des-Neiges","url":"https:\/\/sdc-cotedesneiges.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2020\/05\/logo-sdc-cote-des-neiges.png","contentUrl":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2020\/05\/logo-sdc-cote-des-neiges.png","width":1221,"height":1290,"caption":"SDC C\u00f4te-des-Neiges"},"image":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sdc.cotedesneiges\/","https:\/\/www.instagram.com\/sdc.cotedesneiges\/","https:\/\/www.linkedin.com\/company\/sdc-cotedesneiges\/"]}]}},"_links":{"self":[{"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/evenements\/19692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/evenements"}],"about":[{"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/types\/evenements"}],"version-history":[{"count":2,"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/evenements\/19692\/revisions"}],"predecessor-version":[{"id":20338,"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/evenements\/19692\/revisions\/20338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/media\/19686"}],"wp:attachment":[{"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/media?parent=19692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}