{"id":19353,"date":"2022-11-25T16:36:01","date_gmt":"2022-11-25T21:36:01","guid":{"rendered":"https:\/\/sdc-cotedesneiges.ca\/evenements\/projection-village-de-noel-2-0\/"},"modified":"2022-12-21T11:10:16","modified_gmt":"2022-12-21T16:10:16","slug":"projection-village-de-noel-2-0","status":"publish","type":"evenements","link":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/","title":{"rendered":"Projection : Village de No\u00ebl 2.0"},"content":{"rendered":"\n<p>Pour une 3e ann\u00e9e cons\u00e9cutive, la SDC C\u00f4te-des-Neiges pr\u00e9sente son Village de No\u00ebl 2.0. Une projection vid\u00e9o ext\u00e9rieure en format g\u00e9ant sur le mur Sud du 5450 C\u00f4te-des-Neiges, juste au-dessus du Pub McCarold\u2019s. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>(Re)d\u00e9couvrez la projection num\u00e9rique au coin de l\u2019avenue Lacombe et C\u00f4te-des-Neiges, tous les soirs du entre 16h et 23h jusqu\u2019au 15 d\u00e9cembre. La projection du Village de No\u00ebl 2.0 s\u2019inscrit dans le parcours hivernal Sentier-des-Neiges, une initiative de la SDC C\u00f4te-des-Neiges qui permet d\u2019animer et d\u2019illuminer le quartier cet hiver.<\/p>\n\n\n\n<p>Consultez l&#8217;\u00e9v\u00e9venement Facebook en cliquant :<a href=\"https:\/\/fb.me\/e\/3bbsCmOvz?utm_source=hs_email&amp;utm_medium=email&amp;_hsenc=p2ANqtz-9bv0tnFZ8ppYSKQQqVO74N8qQPf1bkDNMbwCS9Bmzy7HScICBrAhpG_8txGLVLSVeFqJqD\" target=\"_blank\" rel=\"noreferrer noopener\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-bleu-color\">&nbsp;ici<\/mark><\/a><\/p>\n\n\n\n<p><em>Merci \u00e0 nos collaborateurs : <\/em><em>Pub McCarold et 5450 C\u00f4te-des-Neiges Holdings Inc.&nbsp;<\/em><\/p>\n\n\n\n<p>Bon visionnement !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour une 3e ann\u00e9e cons\u00e9cutive, la SDC C\u00f4te-des-Neiges pr\u00e9sente son Village de No\u00ebl 2.0. Une&#8230; <a class=\"read-more\" href=\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/\">Read More <i class=\"fas fa-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"featured_media":19352,"menu_order":105,"template":"","class_list":["post-19353","evenements","type-evenements","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Projection : Village de No\u00ebl 2.0 - SDC C\u00f4te-des-Neiges<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projection : Village de No\u00ebl 2.0 - SDC C\u00f4te-des-Neiges\" \/>\n<meta property=\"og:description\" content=\"Pour une 3e ann\u00e9e cons\u00e9cutive, la SDC C\u00f4te-des-Neiges pr\u00e9sente son Village de No\u00ebl 2.0. Une... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/\" \/>\n<meta property=\"og:site_name\" content=\"SDC C\u00f4te-des-Neiges\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sdc.cotedesneiges\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T16:10:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/11\/PXL_20221128_2145444322-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/\",\"name\":\"Projection : Village de No\u00ebl 2.0 - SDC C\u00f4te-des-Neiges\",\"isPartOf\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/11\/PXL_20221128_2145444322-scaled.jpg\",\"datePublished\":\"2022-11-25T21:36:01+00:00\",\"dateModified\":\"2022-12-21T16:10:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#primaryimage\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/11\/PXL_20221128_2145444322-scaled.jpg\",\"contentUrl\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/11\/PXL_20221128_2145444322-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/sdc-cotedesneiges.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projection : Village de No\u00ebl 2.0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#website\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/en\/\",\"name\":\"SDC C\u00f4te-des-Neiges\",\"description\":\"Organisme \u00e0 but non-lucratif cr\u00e9\u00e9 en 2018, la SDC C\u00f4te-des-Neiges regroupe 230 commer\u00e7ants et professionnels.\",\"publisher\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sdc-cotedesneiges.ca\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#organization\",\"name\":\"SDC C\u00f4te-des-Neiges\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2020\/05\/logo-sdc-cote-des-neiges.png\",\"contentUrl\":\"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2020\/05\/logo-sdc-cote-des-neiges.png\",\"width\":1221,\"height\":1290,\"caption\":\"SDC C\u00f4te-des-Neiges\"},\"image\":{\"@id\":\"https:\/\/sdc-cotedesneiges.ca\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/sdc.cotedesneiges\/\",\"https:\/\/www.instagram.com\/sdc.cotedesneiges\/\",\"https:\/\/www.linkedin.com\/company\/sdc-cotedesneiges\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projection : Village de No\u00ebl 2.0 - SDC C\u00f4te-des-Neiges","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/","og_locale":"en_US","og_type":"article","og_title":"Projection : Village de No\u00ebl 2.0 - SDC C\u00f4te-des-Neiges","og_description":"Pour une 3e ann\u00e9e cons\u00e9cutive, la SDC C\u00f4te-des-Neiges pr\u00e9sente son Village de No\u00ebl 2.0. Une... Read More","og_url":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/","og_site_name":"SDC C\u00f4te-des-Neiges","article_publisher":"https:\/\/www.facebook.com\/sdc.cotedesneiges\/","article_modified_time":"2022-12-21T16:10:16+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/11\/PXL_20221128_2145444322-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/","url":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/","name":"Projection : Village de No\u00ebl 2.0 - SDC C\u00f4te-des-Neiges","isPartOf":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#primaryimage"},"image":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#primaryimage"},"thumbnailUrl":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/11\/PXL_20221128_2145444322-scaled.jpg","datePublished":"2022-11-25T21:36:01+00:00","dateModified":"2022-12-21T16:10:16+00:00","breadcrumb":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#primaryimage","url":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/11\/PXL_20221128_2145444322-scaled.jpg","contentUrl":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2022\/11\/PXL_20221128_2145444322-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/events\/projection-village-de-noel-2-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sdc-cotedesneiges.ca\/en\/"},{"@type":"ListItem","position":2,"name":"Projection : Village de No\u00ebl 2.0"}]},{"@type":"WebSite","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#website","url":"https:\/\/sdc-cotedesneiges.ca\/en\/","name":"SDC C\u00f4te-des-Neiges","description":"Organisme \u00e0 but non-lucratif cr\u00e9\u00e9 en 2018, la SDC C\u00f4te-des-Neiges regroupe 230 commer\u00e7ants et professionnels.","publisher":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sdc-cotedesneiges.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#organization","name":"SDC C\u00f4te-des-Neiges","url":"https:\/\/sdc-cotedesneiges.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2020\/05\/logo-sdc-cote-des-neiges.png","contentUrl":"https:\/\/sdc-cotedesneiges.ca\/wp-content\/uploads\/2020\/05\/logo-sdc-cote-des-neiges.png","width":1221,"height":1290,"caption":"SDC C\u00f4te-des-Neiges"},"image":{"@id":"https:\/\/sdc-cotedesneiges.ca\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sdc.cotedesneiges\/","https:\/\/www.instagram.com\/sdc.cotedesneiges\/","https:\/\/www.linkedin.com\/company\/sdc-cotedesneiges\/"]}]}},"_links":{"self":[{"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/evenements\/19353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/evenements"}],"about":[{"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/types\/evenements"}],"version-history":[{"count":6,"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/evenements\/19353\/revisions"}],"predecessor-version":[{"id":19811,"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/evenements\/19353\/revisions\/19811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/media\/19352"}],"wp:attachment":[{"href":"https:\/\/sdc-cotedesneiges.ca\/en\/wp-json\/wp\/v2\/media?parent=19353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}